{"id":10697,"date":"2023-05-22T10:38:47","date_gmt":"2023-05-22T09:38:47","guid":{"rendered":"https:\/\/truyol.com/blog\/?p=10697"},"modified":"2024-09-05T17:26:37","modified_gmt":"2024-09-05T15:26:37","slug":"tecnicas-para-disenar-tarjetas-de-visita-innovadoras","status":"publish","type":"post","link":"https:\/\/truyol.com\/blog\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\/","title":{"rendered":"T\u00e9cnicas para dise\u00f1ar tarjetas de visita innovadoras"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10697\" class=\"elementor elementor-10697\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3998e4c8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3998e4c8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-44c30b34\" data-id=\"44c30b34\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60f96647 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"60f96647\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>\u00cdndice<\/strong>\n\n \t<li><a href=\"#tarjetas_visita_innovadoras_texturaGF\">Tarjetas de visita con textura<\/a><\/li>\n \t<li style=\"text-align: left;\"><a href=\"#tarjetas_visita_innovadoras_multicapa\">Tarjetas de visita multicapa<\/a><\/li>\n \t<li><a href=\"#tarjetas_visita_innovadoras_3D\">Tarjetas de visita en 3D<\/a><\/li>\n \t<li><a href=\"#tarjetas_visita_innovadoras_3DGF\">Tarjetas de visita con materiales de Gran Formato\u00a0<\/a><\/li>\n \t<li><a href=\"#tarjetas_visita_innovadoras_confunda\">Tarjetas de visita con funda<\/a><\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3cda5c1f\" data-id=\"3cda5c1f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d858830 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d858830\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ae9bf1a\" data-id=\"ae9bf1a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc5f4a2 elementor-widget elementor-widget-text-editor\" data-id=\"fc5f4a2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>La evoluci\u00f3n de las tarjetas de visita va a m\u00e1s. Este cl\u00e1sico de los negocios, lejos de ser sustituido por una forma digital de contacto, est\u00e1 sabiendo aprovechar el avance tecnol\u00f3gico y, especialmente, la impresi\u00f3n digital, para seguir sorprendiendo con tarjetas de visita innovadoras.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8f9a9e6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f9a9e6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-77ccd80\" data-id=\"77ccd80\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e10b9b8 elementor-widget elementor-widget-text-editor\" data-id=\"e10b9b8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Las tarjetas de presentaci\u00f3n en papel son insustituibles. Siguen imprimi\u00e9ndose <a href=\"https:\/\/truyol.com\/es\/material-publicitario\/tarjetas-de-visita-clasicas\" target=\"_blank\" rel=\"noopener\">tarjetas de visita cl\u00e1sicas<\/a> con dise\u00f1os muy potentes. No obstante, complementarla con <a href=\"https:\/\/truyol.com\/es\/material-publicitario\/tarjetas-de-visita-personalizadas\" target=\"_blank\" rel=\"noopener\">un papel creativo<\/a>, aplicar un acabado especial como las <a href=\"https:\/\/truyol.com\/es\/material-publicitario\/tarjetas-de-visita-estampadas\" target=\"_blank\" rel=\"noopener\">tarjetas estampadas<\/a>, una tinta directa con las <a href=\"https:\/\/truyol.com\/es\/material-publicitario\/tarjetas-de-visita-con-tinta-metalizada\" target=\"_blank\" rel=\"noopener\">tarjetas de visita con tinta metalizada<\/a>, o relieve suponen un coste extra \u00ednfimo. Mucho m\u00e1s cuando este peque\u00f1o detalle reporta una <strong>imagen \u00fanica y diferenciadora<\/strong> a la empresa con tarjetas de visita innovadoras.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0ae4ded elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0ae4ded\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-336189b\" data-id=\"336189b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d3e868 elementor-widget elementor-widget-text-editor\" data-id=\"3d3e868\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Las tarjetas de visita ya no son un mero contenedor de datos, son la tarjeta de presentaci\u00f3n de cualquier negocio. Este aspecto le hace adquirir toda la relevancia. Preg\u00fantate <strong>qu\u00e9 imagen quieres proyectar como profesional.<\/strong> Puedes ser una empresa m\u00e1s y pasar desapercibida, o puedes ser \u201cla empresa que\u2026\u201d.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f936b83 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f936b83\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-30f4db2\" data-id=\"30f4db2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a310fa elementor-widget elementor-widget-text-editor\" data-id=\"9a310fa\" data-element_type=\"widget\" id=\"tarjetas_visita_innovadoras_texturaGF\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>La gran novedad: Tarjetas de visita con textura <\/strong><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0516b2a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0516b2a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7042ddd\" data-id=\"7042ddd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ee4707 elementor-widget elementor-widget-image\" data-id=\"2ee4707\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1600\" height=\"933\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2023\/05\/imprimir-tarjetas-de-visita-innovadoras-y-creativas.jpg\" class=\"attachment-full size-full wp-image-10703\" alt=\"t\u00e9cnicas para dise\u00f1ar tarjetas de visita innovadoras\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Tarjeta de visita con textura y esquinas redondeadas para un estudio de dise\u00f1o ficticio.  <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fea06db elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fea06db\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-76b96fa\" data-id=\"76b96fa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68731a3 elementor-widget elementor-widget-text-editor\" data-id=\"68731a3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Solo hace falta una b\u00fasqueda en Google para comprobar la forma m\u00e1s com\u00fan de las tarjetas de visita con textura. Se ofrecen papeles verjurados, marcados a fieltro o gofrados. Este recurso es sensacional,<strong> un papel creativo es capaz de abanderar a una empresa.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-444a905 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"444a905\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b5824e\" data-id=\"5b5824e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a6918fe elementor-widget elementor-widget-text-editor\" data-id=\"a6918fe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sin embargo, en <a href=\"https:\/\/truyol.com\/\" target=\"_blank\" rel=\"noopener\">truyol.com<\/a> hemos ido m\u00e1s all\u00e1 desarrollando, en exclusiva, <strong>una nueva t\u00e9cnica de impresi\u00f3n para tarjetas de visita<\/strong> <strong>que solo encontrar\u00e1s en nuestra imprenta online.<\/strong> Y es que nos apasiona tanto la impresi\u00f3n digital y todas sus posibilidades que no paramos de idear nuevas f\u00f3rmulas para reinventar elementos tan cl\u00e1sicos como las tarjetas de visita, <a href=\"https:\/\/truyol.com\/es\/material-publicitario\/folletos-especiales\" target=\"_blank\" rel=\"noopener\">los folletos<\/a> o <a href=\"https:\/\/truyol.com\/es\/material-publicitario\/displays\" target=\"_blank\" rel=\"noopener\">los displays publicitarios<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f67c8e0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f67c8e0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f8de64e\" data-id=\"f8de64e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1372599 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"1372599\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2023\/05\/imprimir-tarjetas-de-visita-innovadoras-con-relieve.jpg\" alt=\"tarjeta de visita con textura\" \/><figcaption class=\"elementor-image-carousel-caption\">La tarjeta de visita se ha impreso sobre el papel creativo X-Per Premium White 320 g. <\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2023\/05\/imprimir-tarjetas-de-visita-innovadoras-con-textura-tinta.blanca.jpg\" alt=\"tarjeta de visita con textura\" \/><figcaption class=\"elementor-image-carousel-caption\">La textura de tinta blanca se aplica en una de las caras. <\/figcaption><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0649f81 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0649f81\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-19d472d\" data-id=\"19d472d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8928f3e elementor-widget elementor-widget-text-editor\" data-id=\"8928f3e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El objetivo es ofrecer herramientas innovadoras que ayude a nuestros clientes a comunicar su esencia a trav\u00e9s de la diferenciaci\u00f3n, a destacar y a hacer m\u00e1s efectivas sus acciones. Porque <strong>lo nuevo, siempre capta la atenci\u00f3n del p\u00fablico.\u00a0<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-332f5d1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"332f5d1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8276604\" data-id=\"8276604\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4623733 elementor-widget elementor-widget-text-editor\" data-id=\"4623733\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Un dato curioso de estas <a href=\"https:\/\/truyol.com\/es\/material-publicitario\/tarjetas-de-visita-con-textura\" target=\"_blank\" rel=\"noopener\">tarjetas de visita con textura<\/a> <\/strong>es que se imprimen con tecnolog\u00eda de Gran Formato. S\u00ed, as\u00ed como lo lees. Imprimimos pliegos de papel con m\u00e1quinas dise\u00f1adas para materiales r\u00edgidos y flexibles.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72e9d0d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72e9d0d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b42bb70\" data-id=\"b42bb70\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30d9764 elementor-widget elementor-widget-text-editor\" data-id=\"30d9764\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Las tarjetas de visita con textura se crean en dos pasos. En primer lugar, se imprime el pliego en CMYK para despu\u00e9s, aplicar la textura. Este volumen se crea mediante capas de tinta blanca superpuestas. La impresi\u00f3n en CMYK se suele realizar con maquinaria para hoja, ya que el Gran Formato no est\u00e1 preparado para la reproducci\u00f3n de detalles o tipograf\u00edas finas. A continuaci\u00f3n, los pliegos se trasladan a Gran Formato donde se termina de imprimir la tarjeta de visita con capas de tinta blanca. En un \u00faltimo paso, se llevan los pliegos al troquel l\u00e1ser para darle la forma exterior.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bcae655 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bcae655\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c88ebcd\" data-id=\"c88ebcd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bae559 elementor-widget elementor-widget-video\" data-id=\"2bae559\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/8DYOjFa7D_g&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-572ce73 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"572ce73\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7f20160\" data-id=\"7f20160\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aaa1ee4 elementor-widget elementor-widget-text-editor\" data-id=\"aaa1ee4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Papeles creativos para estimular las sensaciones t\u00e1ctiles<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ed5d27e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ed5d27e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b22fe9\" data-id=\"5b22fe9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3967cf8 elementor-widget elementor-widget-text-editor\" data-id=\"3967cf8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Otro redoble para estas innovadoras <strong>tarjetas de visita con textura de tinta blanca<\/strong> es que pueden combinarse con todo tipo de papeles creativos: de color, papeles texturizados e, incluso, perlados.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-16bb6d1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"16bb6d1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1801666\" data-id=\"1801666\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f41ae7 elementor-widget elementor-widget-text-editor\" data-id=\"2f41ae7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En este caso, se ha seleccionado el X-Per Premium White 320 g para las tarjetas de visita de un estudio de dise\u00f1o gr\u00e1fico ficticio llamado Pupa. Este papel creativo aporta una sensaci\u00f3n natural al tacto, a la vez que dispone de un extraordinario resultado de impresi\u00f3n totalmente n\u00edtido y brillante, ideal para tarjetas a todo color. Aqu\u00ed, la textura de tinta blanca se ha aplicado en masa para la tirita, salvando los peque\u00f1os orificios, y detalles de l\u00edneas y puntos que simulan una herida. Desde luego, son unas tarjetas de visita innovadoras, muy originales y poco comunes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-917a77b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"917a77b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42919bb\" data-id=\"42919bb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c6bcf6 elementor-widget elementor-widget-image\" data-id=\"7c6bcf6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1600\" height=\"933\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2023\/05\/diseno-tarjetas-de-visita-originales-con-textura.jpg\" class=\"attachment-full size-full wp-image-10718\" alt=\"t\u00e9cnicas para dise\u00f1ar tarjetas de visita innovadoras\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Tarjeta de visita con textura impresa sobre el papel creativo Sirio Dark Blue 290 g. <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1987d9c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1987d9c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ce6f63c\" data-id=\"ce6f63c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1cde6dc elementor-widget elementor-widget-image\" data-id=\"1cde6dc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1600\" height=\"933\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2023\/05\/diseno-tarjetas-de-visita-originales-con-textura-en-relieve.jpg\" class=\"attachment-full size-full wp-image-10719\" alt=\"t\u00e9cnicas para imprimir tarjetas de visita innovadoras\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Es posible imprimir trazos de 0,5 mm o aplicar la textura con tinta blanca en grandes masas. <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7041a7b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7041a7b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b01f02c\" data-id=\"b01f02c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0fa085f elementor-widget elementor-widget-text-editor\" data-id=\"0fa085f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Con las tarjetas de presentaci\u00f3n de este estudio de arquitectura ficticio, se busca proyectar una imagen m\u00e1s elegante y sofisticada, pero igualmente transformadora. Para potenciar estos aspectos se ha elegido el papel Sirio Dark Blue 290 g que est\u00e1 tintado sin estucar lo que le da una sensaci\u00f3n org\u00e1nica al tacto que, combinada con las finas l\u00edneas de topograf\u00eda, nos trasladan un sinf\u00edn de sensaciones placenteras que, autom\u00e1ticamente, se asocian al estudio.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-03e8578 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"03e8578\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-148832d\" data-id=\"148832d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b22b33d elementor-widget elementor-widget-text-editor\" data-id=\"b22b33d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Para Desnivel se ha enmarcado parte de la textura de manera intencionada. El objetivo es recalcar la irregularidad de cualquier terreno con relieve. El resultado de un marco en una tarjeta de visita nunca va a ser exacto, por lo que recomendamos no incluirlo a no ser que sea un requerimiento del concepto como en este ejemplo. <a href=\"https:\/\/truyol.com\/blog\/2022\/09\/02\/diseno-de-tarjetas-de-visita-6-soluciones-para-una-buena-impresion\/\" target=\"_blank\" rel=\"noopener\">Consulta los consejos antes de dise\u00f1ar tarjetas de visita.<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0d2681e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0d2681e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-88faf06\" data-id=\"88faf06\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5434a6e elementor-widget elementor-widget-text-editor\" data-id=\"5434a6e\" data-element_type=\"widget\" id=\"tarjetas_visita_innovadoras_multicapa\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>La evoluci\u00f3n de las tarjetas de visita multicapa<\/strong><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4dc75bf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4dc75bf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5be7333\" data-id=\"5be7333\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-275f094 elementor-widget elementor-widget-text-editor\" data-id=\"275f094\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/truyol.com\/es\/material-publicitario\/tarjetas-y-tarjetones-multicapa\" target=\"_blank\" rel=\"noopener\">Las tarjetas de visita multicapa<\/a> han evolucionado para incrementar los est\u00edmulos t\u00e1ctiles. Este modelo destacaba por su gran rigidez y grosor, proyectando una imagen de solidez y confianza en el negocio.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ce67ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ce67ff\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d9f44f2\" data-id=\"d9f44f2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b89e9ff elementor-widget elementor-widget-text-editor\" data-id=\"b89e9ff\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ahora, incluyen m\u00e1s posibilidades como crear <strong>troqueles internos para jugar con los colores y las texturas del papel, <\/strong>o la posibilidad de aplicar acabados como barniz selectivo o stamping.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc8e2fb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc8e2fb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-276518c\" data-id=\"276518c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-885859d elementor-widget elementor-widget-image\" data-id=\"885859d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"867\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2023\/05\/imprimir-tarjetas-de-visita-innovadoras-multicapa-con-canto-pintado.jpg\" class=\"attachment-full size-full wp-image-10726\" alt=\"t\u00e9cnicas para dise\u00f1ar tarjetas de visita innovadoras\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Tarjeta de visita multicapa con cantos pintados para un restaurante.  <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1e6ced3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1e6ced3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3c6adaf\" data-id=\"3c6adaf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1f9fc0 elementor-widget elementor-widget-text-editor\" data-id=\"d1f9fc0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Adem\u00e1s, el <strong>enorme cat\u00e1logo de papeles disponible para combinar<\/strong> permite plasmar cualquier personalidad o concepto en la tarjeta de presentaci\u00f3n. Las tarjetas de visita multicapa para un restaurante ficticio llamado \u201cLa Siesta\u201d se han formado con el papel Woodstock Betulla 285 g para las capas exteriores y el Sirio Dark Blue, esta vez de 700 g, especialmente indicado para la capa central que se deja ver a trav\u00e9s de los troqueles internos en forma de jarrones de cer\u00e1mica.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-83b40b7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"83b40b7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4da1e63\" data-id=\"4da1e63\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a38345 elementor-widget elementor-widget-text-editor\" data-id=\"8a38345\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El Woodstock Betulla de color crema se fabrica con un 80% de fibras recicladas y un 20% de fibras v\u00edrgenes libres de cloro, que se pueden apreciar en su naturaleza org\u00e1nica. Este papel es completamente reciclable y biodegradable. El gramaje total de esta tarjeta de visita multicapa es de 1.270 g.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bdc3f5b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bdc3f5b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-17d9584\" data-id=\"17d9584\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6fe503 elementor-widget elementor-widget-image\" data-id=\"f6fe503\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"867\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2023\/05\/imprimir-tarjetas-de-visita-innovadoras-multicapa-con-troquel.jpg\" class=\"attachment-full size-full wp-image-10727\" alt=\"tarjeta de visita multicapa\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Se ha combinado un papel natural fabricado con fibras para el exterior con un papel de color en la capa central. <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-51952b4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"51952b4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dcf822a\" data-id=\"dcf822a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9753600 elementor-widget elementor-widget-text-editor\" data-id=\"9753600\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Los detalles son importantes, mucho m\u00e1s en un dise\u00f1o de estas dimensiones. \u00a0Estas tarjetas de presentaci\u00f3n multicapa se han rematado <strong>pintando los cantos de color naranja,<\/strong> uno de los tantos colores disponibles. Al ser tan dark la capa central, no ha cogido la intensidad del naranja dando como resultado un perfecto s\u00e1ndwich.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-03ecd7d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"03ecd7d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-75da4dc\" data-id=\"75da4dc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e26294 elementor-widget elementor-widget-image\" data-id=\"7e26294\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"933\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2023\/05\/imprimir-tarjetas-de-visita-innovadoras-con-packaging.jpg\" class=\"attachment-full size-full wp-image-10724\" alt=\"tarjeta de regalo m\u00fasica streaming\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Tarjeta de regalo para una plataforma de m\u00fasica en streaming con caja personalizada. <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a057c9f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a057c9f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c187a9e\" data-id=\"c187a9e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6247618 elementor-widget elementor-widget-text-editor\" data-id=\"6247618\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En contraposici\u00f3n, se han impreso unas <strong>tarjetas de regalo multicapa<\/strong> con la suscripci\u00f3n a una plataforma digital de m\u00fasica en streaming. Para presentar este obsequio dirigido a amantes de la m\u00fasica, la tarjeta de regalo multicapa se entrega en una caja automontable con cuna que se ha impreso con una plantilla a medida a trav\u00e9s de <a href=\"https:\/\/truyol.com\/es\/packaging-folding-carton\/carton-personalizado\" target=\"_blank\" rel=\"noopener\">packaging personalizado.<\/a> La clientela puede personalizar la caja con el nombre del destinatario o destinataria del obsequio y su canci\u00f3n m\u00e1s especial.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0299640 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0299640\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e30a3f0\" data-id=\"e30a3f0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d68f67 elementor-widget elementor-widget-text-editor\" data-id=\"3d68f67\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Al igual que el packaging, la tarjeta de regalo multicapa tiene <strong>stamping plata 2D<\/strong> en el anverso. Por la otra cara, se han realizado unos cortes internos que simulan un sonograma.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4f5aa72 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4f5aa72\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f02928c\" data-id=\"f02928c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-788d08d elementor-widget elementor-widget-image\" data-id=\"788d08d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"933\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2023\/05\/imprimir-tarjetas-de-visita-innovadoras-con-acabados-especiales.jpg\" class=\"attachment-full size-full wp-image-10723\" alt=\"tarjeta de regalo\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Tarjeta de regalo multicapa con stamping plata 2D. <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8c5a722 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8c5a722\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6762278\" data-id=\"6762278\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f721940 elementor-widget elementor-widget-image\" data-id=\"f721940\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"934\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2023\/05\/imprimir-tarjetas-de-visita-innovadoras-con-troquelado.jpg\" class=\"attachment-full size-full wp-image-10725\" alt=\"tarjeta de visita multicapa\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Detalle de la profundidad del troquel. Se observa, adem\u00e1s, la combinaci\u00f3n de papeles. <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b40d48f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b40d48f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b390a9b\" data-id=\"b390a9b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33243d0 elementor-widget elementor-widget-text-editor\" data-id=\"33243d0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Para la tarjeta regalo de esta empresa de streaming musical, se han combinado la cartulina gr\u00e1fica Tecknocard 350 g con plastificado mate antiara\u00f1azos para las capas exteriores, con el papel Sirio Ultra Black 680 g para la capa central. Una presentaci\u00f3n de 1.380 g a la altura del mejor regalo. Todo el conjunto hace alusi\u00f3n al mundo digital potenciado con el stamping plateado, asociado a la tecnolog\u00eda.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ed52ebb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ed52ebb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-25fd89f\" data-id=\"25fd89f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39915b1 elementor-widget elementor-widget-text-editor\" data-id=\"39915b1\" data-element_type=\"widget\" id=\"tarjetas_visita_innovadoras_3D\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>Tarjetas de visita innovadoras en 3D<\/strong><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f338c86 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f338c86\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-437bbd1\" data-id=\"437bbd1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-619259b elementor-widget elementor-widget-text-editor\" data-id=\"619259b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Algo tan sencillo como <strong>salirse del formato habitual o descontextualizar las tarjetas<\/strong> <strong>de visita<\/strong> es un acierto para darle un toque innovador a la presentaci\u00f3n. En este caso, el protagonista absoluto es el troquel. Esa herramienta que nos ayuda a darle forma al papel, o generar pliegues con su hendido.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cad2cea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cad2cea\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-420819d\" data-id=\"420819d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8bcbdac elementor-widget elementor-widget-image\" data-id=\"8bcbdac\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"867\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2023\/05\/diseno-tarjetas-de-visita-originales-dobladas.jpg\" class=\"attachment-full size-full wp-image-10728\" alt=\"tarjetas de visita de varios colores\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Tarjeta de visita con formato triangular pedida con la opci\u00f3n multimodelo de truyol.com. <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d41fc0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d41fc0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aa576a7\" data-id=\"aa576a7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d4ad35 elementor-widget elementor-widget-text-editor\" data-id=\"3d4ad35\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Estas <strong><a href=\"https:\/\/truyol.com\/es\/material-publicitario\/tarjetas-de-visita-troqueladas\" target=\"_blank\" rel=\"noopener\">tarjetas de visita troqueladas<\/a><\/strong> tienen las dimensiones habituales de una tarjeta de visita est\u00e1ndar, pero en formato cuadrado. Para darle un estilo muy diferente, se ha hendido al medio convirti\u00e9ndola en una tarjeta de visita con forma de tri\u00e1ngulo is\u00f3sceles. \u00a0As\u00ed, las tarjetas de visita troqueladas adquieren dimensi\u00f3n 3D.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6894a80 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6894a80\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f650954\" data-id=\"f650954\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78bb62d elementor-widget elementor-widget-text-editor\" data-id=\"78bb62d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Este branding pertenece a Fiero Hostel, un negocio ficticio dirigido a personas j\u00f3venes. Las tarjetas est\u00e1n impresas sobre el creativo Old Mill Premium White de 300g, un papel sin estucar marcado a fieltro por ambas caras para enfatizar su car\u00e1cter ecol\u00f3gico, pero con una reproducci\u00f3n de las tintas muy potente y brillante.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e9bb0ce elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e9bb0ce\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d502f88\" data-id=\"d502f88\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c3c808d elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"c3c808d\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2023\/05\/diseno-tarjetas-de-visita-originales-dobladas-en-diagonal.jpg\" alt=\"tarjeta de visita con hendido\" \/><figcaption class=\"elementor-image-carousel-caption\">La tarjeta adquiere volumen 3D gracias al hendido. <\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2023\/05\/diseno-tarjetas-de-visita-originales-dobladas-a-la-mitad.jpg\" alt=\"tarjeta de visita troquelada\" \/><figcaption class=\"elementor-image-carousel-caption\">La tarjeta se ha impreso sobre el papel creativo Old Mill Premium White de 300g con una impresionante vivacidad de los colores.<\/figcaption><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3bd18a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3bd18a2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61eba88\" data-id=\"61eba88\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b70924 elementor-widget elementor-widget-text-editor\" data-id=\"6b70924\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Se han impreso varias versiones con colores saturados para hacer m\u00e1s llamativa la presentaci\u00f3n. Por cierto, \u00bfhas probado ya el <a href=\"https:\/\/youtu.be\/XmHPzsClPoc\" target=\"_blank\" rel=\"noopener\">pedido multimodelo<\/a>? Permite imprimir varios dise\u00f1os diferentes, siempre que tengan la misma forma y las mismas caracter\u00edsticas de configuraci\u00f3n.<strong> Por poco m\u00e1s de 20\u20ac, hemos pedido 4 modelos con colores diferentes.\u00a0<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8e30579 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8e30579\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9fb0d0f\" data-id=\"9fb0d0f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7cb6e32 elementor-widget elementor-widget-image\" data-id=\"7cb6e32\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"867\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2023\/05\/diseno-tarjetas-de-visita-originales-dobladas-soporte-con-textura.jpg\" class=\"attachment-full size-full wp-image-10731\" alt=\"tarjeta de visita con papel creativo\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Detalle de la textura marcada a fieltro por ambas caras del Old Mill Premium White de 300g.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-877d901 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"877d901\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5c1fcfd\" data-id=\"5c1fcfd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd045a4 elementor-widget elementor-widget-text-editor\" data-id=\"fd045a4\" data-element_type=\"widget\" id=\"tarjetas_visita_innovadoras_3DGF\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Innovaci\u00f3n desde el material<\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3de4848 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3de4848\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aa131ad\" data-id=\"aa131ad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ba2558 elementor-widget elementor-widget-text-editor\" data-id=\"6ba2558\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Otra f\u00f3rmula para romper con lo est\u00e1ndar y descontextualizar las tarjetas de visita es <strong>elegir un material diferente al papel.<\/strong> Lo reconocemos, \u00a1nos encanta! Esta soluci\u00f3n ya la hemos dado m\u00e1s veces.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f580153 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f580153\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f82dc6c\" data-id=\"f82dc6c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f89090f elementor-widget elementor-widget-text-editor\" data-id=\"f89090f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hemos impreso <a href=\"https:\/\/truyol.com\/blog\/2021\/11\/08\/tarjetas-de-visita-pospandemia-para-reactivar-la-actividad\/\" target=\"_blank\" rel=\"noopener\">tarjetas de visita sobre polipropileno alveolar<\/a>, el soporte que se utiliza para la carteler\u00eda inmobiliaria, <a href=\"https:\/\/truyol.com\/blog\/2019\/09\/12\/cinco-tarjetas-de-visita-para-inspirarte-soportes-tintas-acabados-y-mucha-creatividad\/\" target=\"_blank\" rel=\"noopener\">tarjetas de PVC con adhesivo reposicionable,<\/a> <a href=\"https:\/\/truyol.com\/blog\/2020\/07\/08\/seis-tarjetas-de-visita-para-pymes-y-emprendedores\/\" target=\"_blank\" rel=\"noopener\">de metacrilato<\/a>, con papel corcho, con papeles sint\u00e9ticos, o <a href=\"https:\/\/truyol.com\/blog\/2022\/09\/02\/diseno-de-tarjetas-de-visita-6-soluciones-para-una-buena-impresion\/\" target=\"_blank\" rel=\"noopener\">en cart\u00f3n compacto.<\/a> <strong>Esta vez le ha tocado el turno al cart\u00f3n corrugado.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c788188 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c788188\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-14d73a5\" data-id=\"14d73a5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d07fa8e elementor-widget elementor-widget-image\" data-id=\"d07fa8e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"933\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2023\/05\/diseno-tarjetas-de-visita-originales-en-carton-troquelado.jpg\" class=\"attachment-full size-full wp-image-10733\" alt=\"t\u00e9cnicas para dise\u00f1ar tarjetas de visita innovadoras\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Tarjeta de presentaci\u00f3n en cart\u00f3n corrugado para un fabricante de muebles a medida. El tarjet\u00f3n tiene piquetas para desprender piezas. <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d4f3ab elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d4f3ab\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9f73b6e\" data-id=\"9f73b6e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07d7c02 elementor-widget elementor-widget-text-editor\" data-id=\"07d7c02\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La tarjeta se presenta en una pieza de cart\u00f3n corrugado microcanal E blanco de 16 x 14 cm con las <strong>piezas sujetas mediante piquetas,<\/strong> listas para desmoldar y montar. Se trata de una tarjeta de visita 3D con forma de silla impresa sobre cart\u00f3n corrugado, el \u00fanico material r\u00edgido de Gran Formato que se puede hendir.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a3bc865 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a3bc865\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-202f870\" data-id=\"202f870\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d34e810 elementor-widget elementor-widget-text-editor\" data-id=\"d34e810\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bajo la frase \u201cVas a tardar en montar esta silla lo mismo que nosotros en realizar tu proyecto\u201d, esta supuesta f\u00e1brica de mobiliario a medida<strong> anima a sus potenciales clientes a interaccionar con su tarjeta de visita.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-03bf7b4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"03bf7b4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-73e6f74\" data-id=\"73e6f74\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3adc66 elementor-widget elementor-widget-image\" data-id=\"e3adc66\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"933\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2023\/05\/diseno-tarjetas-de-visita-originales-en-carton.jpg\" class=\"attachment-full size-full wp-image-10732\" alt=\"tarjeta de visita en 3D\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Tarjeta de visita en 3D con forma de silla. <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-099f7ef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"099f7ef\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c51378f\" data-id=\"c51378f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c62b45 elementor-widget elementor-widget-text-editor\" data-id=\"1c62b45\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Adem\u00e1s, esta original tarjeta de visita tiene una doble funci\u00f3n para apoyar el m\u00f3vil o cualquier artilugio ya que tiene estabilidad suficiente para aguantar peso.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0e9339c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0e9339c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a840f57\" data-id=\"a840f57\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60464f8 elementor-widget elementor-widget-text-editor\" data-id=\"60464f8\" data-element_type=\"widget\" id=\"tarjetas_visita_innovadoras_confunda\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Tarjetas de presentaci\u00f3n con funda<\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-883f8a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"883f8a2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aa313c8\" data-id=\"aa313c8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb2aabe elementor-widget elementor-widget-image\" data-id=\"cb2aabe\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"933\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2023\/05\/diseno-tarjetas-de-visita-originales-con-funda.jpg\" class=\"attachment-full size-full wp-image-10734\" alt=\"t\u00e9cnicas para dise\u00f1ar tarjetas de visita innovadoras\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Tarjeta de visita con funda troquelada. <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-efd8db0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"efd8db0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ceb881b\" data-id=\"ceb881b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15f10c6 elementor-widget elementor-widget-text-editor\" data-id=\"15f10c6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Otra manera de generar interacci\u00f3n es <strong>dise\u00f1ando una funda para la tarjeta,<\/strong> como si fuese su traje a medida. Esta <strong>tarjeta de visita con esquinas redondeadas<\/strong>\u00a0est\u00e1 impresa sobre un papel estucado mate 350 g y su funda con troqueles internos sobre estucado mate 170 g, ambas con plastificado mate antiara\u00f1azos para asegurarse que permanezca intacta con el paso del tiempo y el roce. Ojo, un gramaje superior para la funda ser\u00eda una mala decisi\u00f3n ya que quedar\u00eda demasiado r\u00edgida al plegarla.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a324b2b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a324b2b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3dc60b1\" data-id=\"3dc60b1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a7106f elementor-widget elementor-widget-text-editor\" data-id=\"2a7106f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Siendo un formato habitual, esta tarjeta de visita con funda genera una presentaci\u00f3n innovadora para una psic\u00f3loga.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c25437a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c25437a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-401c1f5\" data-id=\"401c1f5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2807f86 elementor-widget elementor-widget-image\" data-id=\"2807f86\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"934\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2023\/05\/diseno-tarjetas-de-visita-originales-con-funda-corte-hd.jpg\" class=\"attachment-full size-full wp-image-10735\" alt=\"Tarjeta de visita con funda troquelada.\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">La funda y la tarjeta est\u00e1n impresas en el mismo papel pero con diferentes gramajes. <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a425e2b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a425e2b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f37be84\" data-id=\"f37be84\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9772368 elementor-widget elementor-widget-text-editor\" data-id=\"9772368\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La impresi\u00f3n digital y sus soluciones innovadoras abren todo <a href=\"https:\/\/truyol.com\/blog\/tag\/tarjetas-de-visita\/\" target=\"_blank\" rel=\"noopener\">un mundo de posibilidades<\/a> para <strong>dise\u00f1ar tarjetas de visita innovadoras.\u00a0<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 imagen quieres proyectar? Te damos soluciones para sorprender con las tarjetas de visita. <\/p>\n","protected":false},"author":3,"featured_media":14656,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,5],"tags":[595,63],"class_list":["post-10697","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacados","category-ideas-creativas","tag-acabados-para-imprenta","tag-tarjetas-de-visita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>T\u00e9cnicas para dise\u00f1ar tarjetas de visita innovadoras - Blog Truyol<\/title>\n<meta name=\"description\" content=\"Este cl\u00e1sico de los negocios se reinventa para seguir sorprendiendo con tarjetas de visita innovadoras que impacten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/truyol.com\/blog\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00e9cnicas para dise\u00f1ar tarjetas de visita innovadoras - Blog Truyol\" \/>\n<meta property=\"og:description\" content=\"Este cl\u00e1sico de los negocios se reinventa para seguir sorprendiendo con tarjetas de visita innovadoras que impacten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/truyol.com\/blog\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Truyol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TruyolDigital\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-22T09:38:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-05T15:26:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2023\/05\/imprimir-tarjetas-de-visita-innovadoras-con-textura.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"867\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Truyol\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2023\/05\/imprimir-tarjetas-de-visita-innovadoras-con-textura.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@truyoldigital\" \/>\n<meta name=\"twitter:site\" content=\"@truyoldigital\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Truyol\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\\\/\"},\"author\":{\"name\":\"Truyol\",\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/#\\\/schema\\\/person\\\/687052256b87b8ba29644f9e6839a3cb\"},\"headline\":\"T\u00e9cnicas para dise\u00f1ar tarjetas de visita innovadoras\",\"datePublished\":\"2023-05-22T09:38:47+00:00\",\"dateModified\":\"2024-09-05T15:26:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\\\/\"},\"wordCount\":2096,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/truyol.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Foto-11.jpg\",\"keywords\":[\"acabados para imprenta\",\"tarjetas de visita\"],\"articleSection\":[\"Destacados\",\"Ideas Creativas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/truyol.com\\\/blog\\\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\\\/\",\"url\":\"https:\\\/\\\/truyol.com\\\/blog\\\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\\\/\",\"name\":\"T\u00e9cnicas para dise\u00f1ar tarjetas de visita innovadoras - Blog Truyol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/truyol.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Foto-11.jpg\",\"datePublished\":\"2023-05-22T09:38:47+00:00\",\"dateModified\":\"2024-09-05T15:26:37+00:00\",\"description\":\"Este cl\u00e1sico de los negocios se reinventa para seguir sorprendiendo con tarjetas de visita innovadoras que impacten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/truyol.com\\\/blog\\\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/truyol.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Foto-11.jpg\",\"contentUrl\":\"https:\\\/\\\/truyol.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Foto-11.jpg\",\"width\":1041,\"height\":608,\"caption\":\"t\u00e9cnicas para dise\u00f1ar tarjetas de visita innovadoras\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"https:\\\/\\\/truyol.com\\\/blog\",\"item\":\"https:\\\/\\\/truyol.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00e9cnicas para dise\u00f1ar tarjetas de visita innovadoras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/truyol.com\\\/blog\\\/\",\"name\":\"Blog Truyol\",\"description\":\"Todo lo que puedes hacer con impresi\u00f3n digital\",\"publisher\":{\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/#organization\"},\"alternateName\":\"Blog de Dise\u00f1o Editorial, Branding, Packaging y m\u00e1s\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/truyol.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/#organization\",\"name\":\"Truyol Digital\",\"alternateName\":\"Blog de Impresi\u00f3n Digital, Dise\u00f1o Editorial, Branding, Packaging y m\u00e1s\",\"url\":\"https:\\\/\\\/truyol.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/truyol.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/logo-truyol.png\",\"contentUrl\":\"https:\\\/\\\/truyol.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/logo-truyol.png\",\"width\":130,\"height\":32,\"caption\":\"Truyol Digital\"},\"image\":{\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TruyolDigital\\\/\",\"https:\\\/\\\/x.com\\\/truyoldigital\",\"https:\\\/\\\/www.instagram.com\\\/truyoldigital\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/truyoldigital\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCyVYR3cNfP0HIONCwxSGplA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/#\\\/schema\\\/person\\\/687052256b87b8ba29644f9e6839a3cb\",\"name\":\"Truyol\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/639a3919cfa06cd1ad18f3f33dbcb0ddc278594b472cdeec917e25db5c45ece8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/639a3919cfa06cd1ad18f3f33dbcb0ddc278594b472cdeec917e25db5c45ece8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/639a3919cfa06cd1ad18f3f33dbcb0ddc278594b472cdeec917e25db5c45ece8?s=96&d=mm&r=g\",\"caption\":\"Truyol\"},\"sameAs\":[\"https:\\\/\\\/truyol.com\\\/\"],\"url\":\"https:\\\/\\\/truyol.com\\\/blog\\\/author\\\/marketing\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"T\u00e9cnicas para dise\u00f1ar tarjetas de visita innovadoras - Blog Truyol","description":"Este cl\u00e1sico de los negocios se reinventa para seguir sorprendiendo con tarjetas de visita innovadoras que impacten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/truyol.com\/blog\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\/","og_locale":"es_ES","og_type":"article","og_title":"T\u00e9cnicas para dise\u00f1ar tarjetas de visita innovadoras - Blog Truyol","og_description":"Este cl\u00e1sico de los negocios se reinventa para seguir sorprendiendo con tarjetas de visita innovadoras que impacten.","og_url":"https:\/\/truyol.com\/blog\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\/","og_site_name":"Blog Truyol","article_publisher":"https:\/\/www.facebook.com\/TruyolDigital\/","article_published_time":"2023-05-22T09:38:47+00:00","article_modified_time":"2024-09-05T15:26:37+00:00","og_image":[{"width":1600,"height":867,"url":"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2023\/05\/imprimir-tarjetas-de-visita-innovadoras-con-textura.jpg","type":"image\/jpeg"}],"author":"Truyol","twitter_card":"summary_large_image","twitter_image":"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2023\/05\/imprimir-tarjetas-de-visita-innovadoras-con-textura.jpg","twitter_creator":"@truyoldigital","twitter_site":"@truyoldigital","twitter_misc":{"Escrito por":"Truyol","Tiempo de lectura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/truyol.com\/blog\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\/#article","isPartOf":{"@id":"https:\/\/truyol.com\/blog\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\/"},"author":{"name":"Truyol","@id":"https:\/\/truyol.com\/blog\/#\/schema\/person\/687052256b87b8ba29644f9e6839a3cb"},"headline":"T\u00e9cnicas para dise\u00f1ar tarjetas de visita innovadoras","datePublished":"2023-05-22T09:38:47+00:00","dateModified":"2024-09-05T15:26:37+00:00","mainEntityOfPage":{"@id":"https:\/\/truyol.com\/blog\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\/"},"wordCount":2096,"commentCount":0,"publisher":{"@id":"https:\/\/truyol.com\/blog\/#organization"},"image":{"@id":"https:\/\/truyol.com\/blog\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\/#primaryimage"},"thumbnailUrl":"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2023\/05\/Foto-11.jpg","keywords":["acabados para imprenta","tarjetas de visita"],"articleSection":["Destacados","Ideas Creativas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/truyol.com\/blog\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/truyol.com\/blog\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\/","url":"https:\/\/truyol.com\/blog\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\/","name":"T\u00e9cnicas para dise\u00f1ar tarjetas de visita innovadoras - Blog Truyol","isPartOf":{"@id":"https:\/\/truyol.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/truyol.com\/blog\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\/#primaryimage"},"image":{"@id":"https:\/\/truyol.com\/blog\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\/#primaryimage"},"thumbnailUrl":"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2023\/05\/Foto-11.jpg","datePublished":"2023-05-22T09:38:47+00:00","dateModified":"2024-09-05T15:26:37+00:00","description":"Este cl\u00e1sico de los negocios se reinventa para seguir sorprendiendo con tarjetas de visita innovadoras que impacten.","breadcrumb":{"@id":"https:\/\/truyol.com\/blog\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/truyol.com\/blog\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/truyol.com\/blog\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\/#primaryimage","url":"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2023\/05\/Foto-11.jpg","contentUrl":"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2023\/05\/Foto-11.jpg","width":1041,"height":608,"caption":"t\u00e9cnicas para dise\u00f1ar tarjetas de visita innovadoras"},{"@type":"BreadcrumbList","@id":"https:\/\/truyol.com\/blog\/tecnicas-para-disenar-tarjetas-de-visita-innovadoras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"https:\/\/truyol.com\/blog","item":"https:\/\/truyol.com\/blog\/"},{"@type":"ListItem","position":2,"name":"T\u00e9cnicas para dise\u00f1ar tarjetas de visita innovadoras"}]},{"@type":"WebSite","@id":"https:\/\/truyol.com\/blog\/#website","url":"https:\/\/truyol.com\/blog\/","name":"Blog Truyol","description":"Todo lo que puedes hacer con impresi\u00f3n digital","publisher":{"@id":"https:\/\/truyol.com\/blog\/#organization"},"alternateName":"Blog de Dise\u00f1o Editorial, Branding, Packaging y m\u00e1s","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/truyol.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/truyol.com\/blog\/#organization","name":"Truyol Digital","alternateName":"Blog de Impresi\u00f3n Digital, Dise\u00f1o Editorial, Branding, Packaging y m\u00e1s","url":"https:\/\/truyol.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/truyol.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2025\/12\/logo-truyol.png","contentUrl":"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2025\/12\/logo-truyol.png","width":130,"height":32,"caption":"Truyol Digital"},"image":{"@id":"https:\/\/truyol.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TruyolDigital\/","https:\/\/x.com\/truyoldigital","https:\/\/www.instagram.com\/truyoldigital\/","https:\/\/www.linkedin.com\/company\/truyoldigital","https:\/\/www.youtube.com\/channel\/UCyVYR3cNfP0HIONCwxSGplA"]},{"@type":"Person","@id":"https:\/\/truyol.com\/blog\/#\/schema\/person\/687052256b87b8ba29644f9e6839a3cb","name":"Truyol","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/639a3919cfa06cd1ad18f3f33dbcb0ddc278594b472cdeec917e25db5c45ece8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/639a3919cfa06cd1ad18f3f33dbcb0ddc278594b472cdeec917e25db5c45ece8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/639a3919cfa06cd1ad18f3f33dbcb0ddc278594b472cdeec917e25db5c45ece8?s=96&d=mm&r=g","caption":"Truyol"},"sameAs":["https:\/\/truyol.com\/"],"url":"https:\/\/truyol.com\/blog\/author\/marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/truyol.com/blog\/wp-json\/wp\/v2\/posts\/10697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/truyol.com/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/truyol.com/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/truyol.com/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/truyol.com/blog\/wp-json\/wp\/v2\/comments?post=10697"}],"version-history":[{"count":49,"href":"https:\/\/truyol.com/blog\/wp-json\/wp\/v2\/posts\/10697\/revisions"}],"predecessor-version":[{"id":11155,"href":"https:\/\/truyol.com/blog\/wp-json\/wp\/v2\/posts\/10697\/revisions\/11155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/truyol.com/blog\/wp-json\/wp\/v2\/media\/14656"}],"wp:attachment":[{"href":"https:\/\/truyol.com/blog\/wp-json\/wp\/v2\/media?parent=10697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/truyol.com/blog\/wp-json\/wp\/v2\/categories?post=10697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/truyol.com/blog\/wp-json\/wp\/v2\/tags?post=10697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}