{"id":4035,"date":"2021-07-05T07:17:08","date_gmt":"2021-07-05T07:17:08","guid":{"rendered":"https:\/\/truyol.com\/blog\/?p=4035"},"modified":"2025-05-29T12:26:46","modified_gmt":"2025-05-29T10:26:46","slug":"guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta","status":"publish","type":"post","link":"https:\/\/truyol.com\/blog\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\/","title":{"rendered":"Gu\u00eda t\u00e9cnica para aplicar troquel en el arte final para imprenta"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4035\" class=\"elementor elementor-4035\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f935371 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f935371\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0453751\" data-id=\"0453751\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8874e8 elementor-widget elementor-widget-heading\" data-id=\"b8874e8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">El acabado de troquel en un dise\u00f1o marca la diferencia: puede aplicarse de manera creativa o para dar forma a los productos impresos. Para obtener un resultado \u00f3ptimo, el dise\u00f1ador debe seguir una serie de pautas a la hora de dise\u00f1ar y hacer el arte final. <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-82dd189 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"82dd189\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c501c72\" data-id=\"c501c72\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-294b94d elementor-widget elementor-widget-text-editor\" data-id=\"294b94d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>El troquel con impresi\u00f3n digital<\/strong><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a55c6c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a55c6c9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3846096\" data-id=\"3846096\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a41aca7 elementor-widget elementor-widget-text-editor\" data-id=\"a41aca7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El troquelado de impresi\u00f3n digital es un recurso muy eficaz que suele emplearse para<strong> dar forma exterior a una pieza, para aplicar cortes interiores o para crear hendidos o medios cortes para packaging.<\/strong> Existen varios <a href=\"https:\/\/truyol.com\/blog\/2018\/05\/10\/tipos-de-troquel-que-se-adaptan-a-cada-producto\/\" target=\"_blank\" rel=\"noopener\">tipos de troquel que se adaptan a cada producto.<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0e8e452 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0e8e452\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a344fc1\" data-id=\"a344fc1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff8460a elementor-widget elementor-widget-text-editor\" data-id=\"ff8460a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>En clave creativa, este acabado de impresi\u00f3n digital aporta un toque de distinci\u00f3n y originalidad<\/strong> a la imagen visual corporativa o los elementos de branding. Tambi\u00e9n es muy efectivo para el material publicitario o promocional, y en elementos de comunicaci\u00f3n corporativos, y pr\u00e1ctico para piezas como carteler\u00eda de gran formato.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9b166d8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9b166d8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9f45f3f\" data-id=\"9f45f3f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29bd2c5 elementor-widget elementor-widget-text-editor\" data-id=\"29bd2c5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>C\u00f3mo preparar el arte final para cada tipo de troquel<\/strong><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ad3eb5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1ad3eb5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-422490e\" data-id=\"422490e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b59506 elementor-widget elementor-widget-text-editor\" data-id=\"6b59506\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El dise\u00f1ador debe seguir una serie de pautas en el proceso de preparaci\u00f3n del arte final para el troquelado:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-674d7e7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"674d7e7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4e16530\" data-id=\"4e16530\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a48e40 elementor-widget elementor-widget-text-editor\" data-id=\"2a48e40\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>1- Instala <a href=\"https:\/\/truyol.com\/es\/guias\/tintas\" target=\"_blank\" rel=\"noopener\">la Biblioteca de Tintas T\u00e9cnicas<\/a> de Truyol Digital, esta herramienta te facilitar\u00e1 mucho el trabajo.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e11049 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e11049\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-92f8b32\" data-id=\"92f8b32\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58b915c elementor-widget elementor-widget-text-editor\" data-id=\"58b915c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>2- Una vez realizada la creatividad en Illustrator, se separa el dise\u00f1o en CMYK y las l\u00edneas de troquel en capas independientes. Cada capa se nombra como corresponde: \u201cCMYK\u201d y \u201cCORTE\u201d, tal y como se refleja en el gr\u00e1fico.*<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d80a88f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d80a88f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-282ec3f\" data-id=\"282ec3f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad8764b elementor-widget elementor-widget-image\" data-id=\"ad8764b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1600\" height=\"1225\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-02.jpg\" class=\"attachment-full size-full wp-image-4097\" alt=\"Gu\u00eda t\u00e9cnica para aplicar troquel en el arte final para imprenta\" srcset=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-02.jpg 1600w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-02-300x230.jpg 300w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-02-1024x784.jpg 1024w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-02-768x588.jpg 768w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-02-1536x1176.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d1c83f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d1c83f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0c091bb\" data-id=\"0c091bb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eb71497 elementor-alert-info elementor-widget elementor-widget-alert\" data-id=\"eb71497\" data-element_type=\"widget\" data-widget_type=\"alert.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-alert\" role=\"alert\">\n\n\t\t\t\t\t\t<span class=\"elementor-alert-title\">*<\/span>\n\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-alert-description\">El arte final contendr\u00e1 tantas capas como acabados y tintas especiales se apliquen. Por ejemplo, en el caso de un folleto plegado, el archivo debe componerse de tres capas: CMYK + CORTE + HENDIDO. <\/span>\n\t\t\t\n\t\t\t\t\t\t<button type=\"button\" class=\"elementor-alert-dismiss\" aria-label=\"Descartar esta alerta.\">\n\t\t\t\t\t\t\t\t\t<span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t<\/button>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8a6d3ad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8a6d3ad\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-126406e\" data-id=\"126406e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-480c21a elementor-widget elementor-widget-text-editor\" data-id=\"480c21a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>3- En la capa CORTE, se incluyen las l\u00edneas de troquel y se rellenan con la tinta plana correspondiente desde la Biblioteca de Tintas T\u00e9cnicas de Truyol Digital con la opci\u00f3n de sobreimprimir en trazo:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a9323b2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a9323b2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2a3477d\" data-id=\"2a3477d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d1ce03 elementor-widget elementor-widget-image\" data-id=\"9d1ce03\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1600\" height=\"571\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-03.jpg\" class=\"attachment-full size-full wp-image-4098\" alt=\"Gu\u00eda t\u00e9cnica para aplicar troquel en el arte final para imprenta\" srcset=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-03.jpg 1600w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-03-300x107.jpg 300w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-03-1024x365.jpg 1024w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-03-768x274.jpg 768w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-03-1536x548.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-365c210 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"365c210\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-885bf0c\" data-id=\"885bf0c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-526317d elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"526317d\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tinta Corte: para troquel exterior e interior de peque\u00f1o y gran formato. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tinta Corte Interior: para troquel interior en cajas de packaging folding carton. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tinta Hendido: para las l\u00edneas de hendido en peque\u00f1o y gran formato.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tinta Trepado: para crear l\u00edneas de puntos taladrados en el papel y poder desprender la pieza con facilidad. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tinta Medio Corte: t\u00e9cnica para crear hendidos mediante una serie de cortes parciales que debilitan el papel. Se aplica en packaging para crear hendidos circulares. Tambi\u00e9n se utiliza para crear los kits de adhesivos. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0e6567c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0e6567c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0ef2725\" data-id=\"0ef2725\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a608e5 elementor-widget elementor-widget-image\" data-id=\"7a608e5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1600\" height=\"557\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-07.jpg\" class=\"attachment-full size-full wp-image-4101\" alt=\"Gu\u00eda t\u00e9cnica para aplicar troquel en el arte final para imprenta\" srcset=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-07.jpg 1600w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-07-300x104.jpg 300w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-07-1024x356.jpg 1024w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-07-768x267.jpg 768w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-07-1536x535.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Ejemplo de aplicaci\u00f3n de la tinta t\u00e9cnica \"Medio corte\" para packaging.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ee91ff2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ee91ff2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4814c9e\" data-id=\"4814c9e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-daa024f elementor-widget elementor-widget-text-editor\" data-id=\"daa024f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Ya est\u00e1 listo el arte final con las l\u00edneas de corte y\/o hendido.<\/strong> Ahora solo queda exportar el archivo con <a href=\"https:\/\/truyol.com\/recursos\/checklist\/marcas-de-corte.pdf\" target=\"_blank\" rel=\"noopener\">los Ajustes preestablecidos de PDF de Truyol Digital<\/a> para asegurarnos de que cumple con los requisitos m\u00ednimos de impresi\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8b68b7b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8b68b7b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-36a91a3\" data-id=\"36a91a3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7caec9 elementor-widget elementor-widget-image\" data-id=\"f7caec9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1123\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/troquel-digital.jpg\" class=\"attachment-full size-full wp-image-4104\" alt=\"Gu\u00eda t\u00e9cnica para aplicar troquel en el arte final para imprenta\" srcset=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/troquel-digital.jpg 1600w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/troquel-digital-300x211.jpg 300w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/troquel-digital-1024x719.jpg 1024w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/troquel-digital-768x539.jpg 768w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/troquel-digital-1536x1078.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">L\u00e1mina con corte exterior y un corte interior. <\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1bcbdd1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1bcbdd1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8c5f8c9\" data-id=\"8c5f8c9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ceb9f3 elementor-widget elementor-widget-text-editor\" data-id=\"0ceb9f3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>Especificaciones t\u00e9cnicas seg\u00fan los tipos de troquel en impresi\u00f3n digital <\/strong><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73d68de elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73d68de\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e153733\" data-id=\"e153733\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d20b19 elementor-widget elementor-widget-text-editor\" data-id=\"5d20b19\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A continuaci\u00f3n, t<strong>e facilitamos algunas especificaciones t\u00e9cnicas y las claves para sacar el m\u00e1ximo partido<\/strong> a este acabado de impresi\u00f3n digital.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-69b8b1a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"69b8b1a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c43affe\" data-id=\"c43affe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-066ea15 elementor-widget elementor-widget-text-editor\" data-id=\"066ea15\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>El arte final para troquel de peque\u00f1o formato<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d7f2a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d7f2a2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-32110c5\" data-id=\"32110c5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0a59688 elementor-widget elementor-widget-image\" data-id=\"0a59688\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1016\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/troquel-laser-detalle-1.jpg\" class=\"attachment-full size-full wp-image-4105\" alt=\"https:\/\/truyol.com\/blog\/2021\/06\/10\/como-preparar-el-arte-final-para-barniz-digital\/\" srcset=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/troquel-laser-detalle-1.jpg 1600w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/troquel-laser-detalle-1-300x191.jpg 300w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/troquel-laser-detalle-1-1024x650.jpg 1024w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/troquel-laser-detalle-1-768x488.jpg 768w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/troquel-laser-detalle-1-1536x975.jpg 1536w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/troquel-laser-detalle-1-600x380.jpg 600w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Detalle de l\u00e1mina con Corte HD.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-44208b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"44208b9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8f862b9\" data-id=\"8f862b9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd43626 elementor-widget elementor-widget-text-editor\" data-id=\"fd43626\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Estas son las categor\u00edas disponibles en <a href=\"https:\/\/truyol.com\/\" target=\"_blank\" rel=\"noopener\">truyol.com<\/a> <strong>para los cortes de productos impresos en hoja:<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-afd557b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"afd557b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d2199b0\" data-id=\"d2199b0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9479bbd elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9479bbd\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Corte: Corte exterior de cualquier forma y 2 cortes interiores.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Corte HD: Corte con cualquier forma en contorno exterior y hasta un m\u00e1ximo de 50 cortes interiores.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Corte + hendido: Corte externo de cualquier forma, hasta 2 cortes interiores y hasta 8 hendidos.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Corte + hendido HD: Se contempla corte externo de cualquier forma, hasta 50 cortes interiores y hasta un m\u00e1ximo de 15 hendidos.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-474bc05 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"474bc05\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0fb26ca\" data-id=\"0fb26ca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8d9bdc elementor-widget elementor-widget-image\" data-id=\"a8d9bdc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"357\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-04.jpg\" class=\"attachment-full size-full wp-image-4099\" alt=\"Gu\u00eda t\u00e9cnica para aplicar troquel en el arte final para imprenta\" srcset=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-04.jpg 1600w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-04-300x67.jpg 300w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-04-1024x228.jpg 1024w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-04-768x171.jpg 768w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-04-1536x343.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Tipos de cortes en truyol.com<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cb169c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cb169c7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5562ef95\" data-id=\"5562ef95\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-253f40b2 elementor-widget elementor-widget-text-editor\" data-id=\"253f40b2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"cuadro-gris\"><h3><strong>Recomendaciones para el dise\u00f1ador<\/strong><\/h3><p>La distancia m\u00ednima entre las l\u00edneas de corte debe ser de, al menos, 2mm. Por debajo de esa distancia no se garantiza un correcto acabado del producto.<\/p><p>\u00a1Aviso! El troquel l\u00e1ser para impresiones en hoja puede producir un leve amarillamiento de los bordes, m\u00e1s acusado en los papeles estucados y en los de color blanco m\u00e1s que en los de color.<\/p><\/div><p><!-- \/wp:paragraph --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-edf2244 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"edf2244\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-80deb6d\" data-id=\"80deb6d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-459ff05 elementor-widget elementor-widget-text-editor\" data-id=\"459ff05\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>El arte final para troquel de gran formato<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a01c80c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a01c80c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-de043e7\" data-id=\"de043e7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed0cff2 elementor-widget elementor-widget-text-editor\" data-id=\"ed0cff2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>En el \u00e1rea de gran formato hay dos tipos de troquel,<\/strong> en funci\u00f3n del material a troquelar: el fresado y corte con cuchilla.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-21ee8e0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"21ee8e0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-29cc2c1\" data-id=\"29cc2c1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e88c6dc elementor-widget elementor-widget-text-editor\" data-id=\"e88c6dc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>El troquel con cuchilla est\u00e1 indicado para soportes flexibles y algunos r\u00edgidos con poca dureza y grosor como el cart\u00f3n corrugado.<\/strong> En el caso del cart\u00f3n corrugado, tambi\u00e9n se admite hendido para imprimir packaging o expositores PLV.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ab9a4ee elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ab9a4ee\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5c06e46d\" data-id=\"5c06e46d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eea1ab6 elementor-widget elementor-widget-text-editor\" data-id=\"eea1ab6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"cuadro-gris\">\n<h3><strong>Recomendaciones para el dise\u00f1ador<\/strong><\/h3>\n<p>El corte con cuchilla admite curvas de radio m\u00ednimo de 5 mm.<\/p>\n<\/div>\n<p><!-- \/wp:paragraph --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9bdda28 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9bdda28\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cbfb2f7\" data-id=\"cbfb2f7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea810f7 elementor-widget elementor-widget-image\" data-id=\"ea810f7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"370\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-05.jpg\" class=\"attachment-full size-full wp-image-4100\" alt=\"Gu\u00eda t\u00e9cnica para aplicar troquel en el arte final para imprenta\" srcset=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-05.jpg 1600w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-05-300x69.jpg 300w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-05-1024x237.jpg 1024w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-05-768x178.jpg 768w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-05-1536x355.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-102ee33 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"102ee33\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e7754d\" data-id=\"1e7754d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09630b3 elementor-widget elementor-widget-text-editor\" data-id=\"09630b3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>El troquel fresado<\/strong> se realiza con una herramienta rotativa de diferentes di\u00e1metros, en funci\u00f3n del material que se va a cortar.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-67eb8a1a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"67eb8a1a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-461000c3\" data-id=\"461000c3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40cde60 elementor-widget elementor-widget-text-editor\" data-id=\"40cde60\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><!-- wp:heading {\"level\":3} --><\/p>\n<div class=\"cuadro-gris\">\n<h3><strong>Recomendaciones para el dise\u00f1ador<\/strong><\/h3>\n<p>Este tipo de troquel de gran formato est\u00e1 indicado para soportes r\u00edgidos.<\/p>\n<p>En los materiales r\u00edgidos como metacrilato, polipropileno y dibond, no se realizan pulido de los cantos.<\/p>\n<p>Solo admite el corte perimetral y un corte interior.<\/p>\n<p>El troquel fresado no consigue \u00e1ngulos rectos, quedando la esquina redondeada con un radio de 1,5 mm.<\/p>\n<\/div>\n<p><!-- \/wp:paragraph --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8c782fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8c782fc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a3dc8b3\" data-id=\"a3dc8b3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5719dd elementor-widget elementor-widget-image\" data-id=\"c5719dd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"469\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-08.jpg\" class=\"attachment-full size-full wp-image-4102\" alt=\"Gu\u00eda t\u00e9cnica para aplicar troquel en el arte final para imprenta\" srcset=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-08.jpg 1600w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-08-300x88.jpg 300w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-08-1024x300.jpg 1024w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-08-768x225.jpg 768w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/GUIA-TECNICA-TROQUEL-Truyol-Digital-CC-08-1536x450.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-35a64364 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"35a64364\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6090addd\" data-id=\"6090addd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-430de917 elementor-widget elementor-widget-text-editor\" data-id=\"430de917\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><!-- wp:heading {\"level\":3} --><\/p>\n<div class=\"cuadro-gris\">\n<h3><strong>Otras recomendaciones para el dise\u00f1ador<\/strong><\/h3>\n<p>No colocar elementos importantes como texto, im\u00e1genes o gr\u00e1ficos cerca de las l\u00edneas de troquel para evitar que se corten.<\/p>\n<p>Recuerda a\u00f1adir la l\u00ednea de troquel exterior con un sangrado perimetral de, al menos, 3 mm.<\/p>\n<p>Se recomienda no utilizar marcos cerca de la l\u00ednea de corte ya que el m\u00ednimo desajuste a la hora de guillotinar o troquelar puede hacer que el recuadro quede descentrado visualmente. La distancia m\u00ednima recomendada entre el borde de corte y el marco es de 5 mm.<\/p>\n<p>En el caso de utilizar cualquier plantilla de Truyol, es importante que no se modifique nada de su contenido, tan solo se deber\u00e1 personalizar la gr\u00e1fica en la capa correspondiente.<\/p>\n<p>Consulta el <a href=\"https:\/\/truyol.com\/blog\/2021\/01\/21\/manual-para-preparar-el-arte-final-perfecto-para-imprenta\/\">Manual para preparar el arte final perfecto para imprenta<\/a><\/p>\n<\/div>\n<p><!-- \/wp:paragraph --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34e580e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34e580e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-efcc8d2\" data-id=\"efcc8d2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5968df0 elementor-widget elementor-widget-text-editor\" data-id=\"5968df0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Aplicar una forma poco usual a unas tarjetas de visita facilita la diferenciaci\u00f3n competitiva<\/strong> y sit\u00faa a la empresa o profesional en un lugar privilegiado en la mente del receptor. Un packaging con troquel interior destacar\u00e1 por encima del resto o un expositor PLV atraer\u00e1 a m\u00e1s personas si tiene una forma original.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2dd98dd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2dd98dd\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5b7de92\" data-id=\"5b7de92\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d70ff4 elementor-widget elementor-widget-text-editor\" data-id=\"1d70ff4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Descarga la <a id=\"aaff-troquel\">Gu\u00eda T\u00e9cnica para aplicar los tipos de troquel<\/a> en el arte final para imprenta. \u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e4c15d2\" data-id=\"e4c15d2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-940bf8d elementor-widget elementor-widget-image\" data-id=\"940bf8d\" data-element_type=\"widget\" id=\"aaff-troquel-foto\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1438\" src=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/mockup-portada-guia.png\" class=\"attachment-full size-full wp-image-4106\" alt=\"gu\u00eda t\u00e9cnica troquel arte final\" srcset=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/mockup-portada-guia.png 1600w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/mockup-portada-guia-300x270.png 300w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/mockup-portada-guia-1024x920.png 1024w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/mockup-portada-guia-768x690.png 768w, https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/mockup-portada-guia-1536x1380.png 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>El acabado de troquel en un dise\u00f1o marca la diferencia: puede aplicarse de manera creativa o para dar forma a los productos impresos. <\/p>\n","protected":false},"author":3,"featured_media":14809,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,8],"tags":[595],"class_list":["post-4035","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacados","category-tutoriales","tag-acabados-para-imprenta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gu\u00eda t\u00e9cnica para aplicar troquel en el arte final - Blog Truyol<\/title>\n<meta name=\"description\" content=\"Descubre la aplicaciones del acabado de troquelado. \u2702 Te damos las pautas para crear el arte final con troquel\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/truyol.com\/blog\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gu\u00eda t\u00e9cnica para aplicar troquel en el arte final - Blog Truyol\" \/>\n<meta property=\"og:description\" content=\"Descubre la aplicaciones del acabado de troquelado. \u2702 Te damos las pautas para crear el arte final con troquel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/truyol.com\/blog\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Truyol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TruyolDigital\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-05T07:17:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-29T10:26:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/troquel-laser-detalle-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1016\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Truyol\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/troquel-laser-detalle-2.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@truyoldigital\" \/>\n<meta name=\"twitter:site\" content=\"@truyoldigital\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Truyol\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"TechArticle\",\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\\\/\"},\"author\":{\"name\":\"Truyol\",\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/#\\\/schema\\\/person\\\/687052256b87b8ba29644f9e6839a3cb\"},\"headline\":\"Gu\u00eda t\u00e9cnica para aplicar troquel en el arte final para imprenta\",\"datePublished\":\"2021-07-05T07:17:08+00:00\",\"dateModified\":\"2025-05-29T10:26:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\\\/\"},\"wordCount\":1082,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/truyol.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/troquel-laser-1.jpg\",\"keywords\":[\"acabados para imprenta\"],\"articleSection\":[\"Destacados\",\"Tutoriales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/truyol.com\\\/blog\\\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\\\/\",\"url\":\"https:\\\/\\\/truyol.com\\\/blog\\\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\\\/\",\"name\":\"Gu\u00eda t\u00e9cnica para aplicar troquel en el arte final - Blog Truyol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/truyol.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/troquel-laser-1.jpg\",\"datePublished\":\"2021-07-05T07:17:08+00:00\",\"dateModified\":\"2025-05-29T10:26:46+00:00\",\"description\":\"Descubre la aplicaciones del acabado de troquelado. \u2702 Te damos las pautas para crear el arte final con troquel\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/truyol.com\\\/blog\\\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/truyol.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/troquel-laser-1.jpg\",\"contentUrl\":\"https:\\\/\\\/truyol.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/troquel-laser-1.jpg\",\"width\":1400,\"height\":818,\"caption\":\"Gu\u00eda t\u00e9cnica para aplicar troquel en el arte final para imprenta\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"https:\\\/\\\/truyol.com\\\/blog\",\"item\":\"https:\\\/\\\/truyol.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gu\u00eda t\u00e9cnica para aplicar troquel en el arte final para imprenta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/truyol.com\\\/blog\\\/\",\"name\":\"Blog Truyol\",\"description\":\"Todo lo que puedes hacer con impresi\u00f3n digital\",\"publisher\":{\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/#organization\"},\"alternateName\":\"Blog de Dise\u00f1o Editorial, Branding, Packaging y m\u00e1s\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/truyol.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/#organization\",\"name\":\"Truyol Digital\",\"alternateName\":\"Blog de Impresi\u00f3n Digital, Dise\u00f1o Editorial, Branding, Packaging y m\u00e1s\",\"url\":\"https:\\\/\\\/truyol.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/truyol.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/logo-truyol.png\",\"contentUrl\":\"https:\\\/\\\/truyol.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/logo-truyol.png\",\"width\":130,\"height\":32,\"caption\":\"Truyol Digital\"},\"image\":{\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TruyolDigital\\\/\",\"https:\\\/\\\/x.com\\\/truyoldigital\",\"https:\\\/\\\/www.instagram.com\\\/truyoldigital\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/truyoldigital\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCyVYR3cNfP0HIONCwxSGplA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/truyol.com\\\/blog\\\/#\\\/schema\\\/person\\\/687052256b87b8ba29644f9e6839a3cb\",\"name\":\"Truyol\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/639a3919cfa06cd1ad18f3f33dbcb0ddc278594b472cdeec917e25db5c45ece8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/639a3919cfa06cd1ad18f3f33dbcb0ddc278594b472cdeec917e25db5c45ece8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/639a3919cfa06cd1ad18f3f33dbcb0ddc278594b472cdeec917e25db5c45ece8?s=96&d=mm&r=g\",\"caption\":\"Truyol\"},\"sameAs\":[\"https:\\\/\\\/truyol.com\\\/\"],\"url\":\"https:\\\/\\\/truyol.com\\\/blog\\\/author\\\/marketing\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gu\u00eda t\u00e9cnica para aplicar troquel en el arte final - Blog Truyol","description":"Descubre la aplicaciones del acabado de troquelado. \u2702 Te damos las pautas para crear el arte final con troquel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/truyol.com\/blog\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\/","og_locale":"es_ES","og_type":"article","og_title":"Gu\u00eda t\u00e9cnica para aplicar troquel en el arte final - Blog Truyol","og_description":"Descubre la aplicaciones del acabado de troquelado. \u2702 Te damos las pautas para crear el arte final con troquel","og_url":"https:\/\/truyol.com\/blog\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\/","og_site_name":"Blog Truyol","article_publisher":"https:\/\/www.facebook.com\/TruyolDigital\/","article_published_time":"2021-07-05T07:17:08+00:00","article_modified_time":"2025-05-29T10:26:46+00:00","og_image":[{"width":1600,"height":1016,"url":"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/troquel-laser-detalle-2.jpg","type":"image\/jpeg"}],"author":"Truyol","twitter_card":"summary_large_image","twitter_image":"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/troquel-laser-detalle-2.jpg","twitter_creator":"@truyoldigital","twitter_site":"@truyoldigital","twitter_misc":{"Escrito por":"Truyol","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"TechArticle","@id":"https:\/\/truyol.com\/blog\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\/#article","isPartOf":{"@id":"https:\/\/truyol.com\/blog\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\/"},"author":{"name":"Truyol","@id":"https:\/\/truyol.com\/blog\/#\/schema\/person\/687052256b87b8ba29644f9e6839a3cb"},"headline":"Gu\u00eda t\u00e9cnica para aplicar troquel en el arte final para imprenta","datePublished":"2021-07-05T07:17:08+00:00","dateModified":"2025-05-29T10:26:46+00:00","mainEntityOfPage":{"@id":"https:\/\/truyol.com\/blog\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\/"},"wordCount":1082,"commentCount":0,"publisher":{"@id":"https:\/\/truyol.com\/blog\/#organization"},"image":{"@id":"https:\/\/truyol.com\/blog\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\/#primaryimage"},"thumbnailUrl":"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/troquel-laser-1.jpg","keywords":["acabados para imprenta"],"articleSection":["Destacados","Tutoriales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/truyol.com\/blog\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/truyol.com\/blog\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\/","url":"https:\/\/truyol.com\/blog\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\/","name":"Gu\u00eda t\u00e9cnica para aplicar troquel en el arte final - Blog Truyol","isPartOf":{"@id":"https:\/\/truyol.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/truyol.com\/blog\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\/#primaryimage"},"image":{"@id":"https:\/\/truyol.com\/blog\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\/#primaryimage"},"thumbnailUrl":"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/troquel-laser-1.jpg","datePublished":"2021-07-05T07:17:08+00:00","dateModified":"2025-05-29T10:26:46+00:00","description":"Descubre la aplicaciones del acabado de troquelado. \u2702 Te damos las pautas para crear el arte final con troquel","breadcrumb":{"@id":"https:\/\/truyol.com\/blog\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/truyol.com\/blog\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/truyol.com\/blog\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\/#primaryimage","url":"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/troquel-laser-1.jpg","contentUrl":"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2021\/07\/troquel-laser-1.jpg","width":1400,"height":818,"caption":"Gu\u00eda t\u00e9cnica para aplicar troquel en el arte final para imprenta"},{"@type":"BreadcrumbList","@id":"https:\/\/truyol.com\/blog\/guia-tecnica-para-aplicar-troquel-en-el-arte-final-para-imprenta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"https:\/\/truyol.com\/blog","item":"https:\/\/truyol.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Gu\u00eda t\u00e9cnica para aplicar troquel en el arte final para imprenta"}]},{"@type":"WebSite","@id":"https:\/\/truyol.com\/blog\/#website","url":"https:\/\/truyol.com\/blog\/","name":"Blog Truyol","description":"Todo lo que puedes hacer con impresi\u00f3n digital","publisher":{"@id":"https:\/\/truyol.com\/blog\/#organization"},"alternateName":"Blog de Dise\u00f1o Editorial, Branding, Packaging y m\u00e1s","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/truyol.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/truyol.com\/blog\/#organization","name":"Truyol Digital","alternateName":"Blog de Impresi\u00f3n Digital, Dise\u00f1o Editorial, Branding, Packaging y m\u00e1s","url":"https:\/\/truyol.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/truyol.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2025\/12\/logo-truyol.png","contentUrl":"https:\/\/truyol.com\/blog\/wp-content\/uploads\/2025\/12\/logo-truyol.png","width":130,"height":32,"caption":"Truyol Digital"},"image":{"@id":"https:\/\/truyol.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TruyolDigital\/","https:\/\/x.com\/truyoldigital","https:\/\/www.instagram.com\/truyoldigital\/","https:\/\/www.linkedin.com\/company\/truyoldigital","https:\/\/www.youtube.com\/channel\/UCyVYR3cNfP0HIONCwxSGplA"]},{"@type":"Person","@id":"https:\/\/truyol.com\/blog\/#\/schema\/person\/687052256b87b8ba29644f9e6839a3cb","name":"Truyol","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/639a3919cfa06cd1ad18f3f33dbcb0ddc278594b472cdeec917e25db5c45ece8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/639a3919cfa06cd1ad18f3f33dbcb0ddc278594b472cdeec917e25db5c45ece8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/639a3919cfa06cd1ad18f3f33dbcb0ddc278594b472cdeec917e25db5c45ece8?s=96&d=mm&r=g","caption":"Truyol"},"sameAs":["https:\/\/truyol.com\/"],"url":"https:\/\/truyol.com\/blog\/author\/marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/truyol.com/blog\/wp-json\/wp\/v2\/posts\/4035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/truyol.com/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/truyol.com/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/truyol.com/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/truyol.com/blog\/wp-json\/wp\/v2\/comments?post=4035"}],"version-history":[{"count":87,"href":"https:\/\/truyol.com/blog\/wp-json\/wp\/v2\/posts\/4035\/revisions"}],"predecessor-version":[{"id":16303,"href":"https:\/\/truyol.com/blog\/wp-json\/wp\/v2\/posts\/4035\/revisions\/16303"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/truyol.com/blog\/wp-json\/wp\/v2\/media\/14809"}],"wp:attachment":[{"href":"https:\/\/truyol.com/blog\/wp-json\/wp\/v2\/media?parent=4035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/truyol.com/blog\/wp-json\/wp\/v2\/categories?post=4035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/truyol.com/blog\/wp-json\/wp\/v2\/tags?post=4035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}